{"id":89191,"date":"2025-04-04T11:55:59","date_gmt":"2025-04-04T09:55:59","guid":{"rendered":"https:\/\/faraone.it\/parapetti\/?post_type=balaustre&#038;p=89191"},"modified":"2026-07-14T12:20:58","modified_gmt":"2026-07-14T10:20:58","slug":"maior-evo-one-con-vetro-a-tutta-altezza","status":"publish","type":"balaustre","link":"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-one-con-vetro-a-tutta-altezza\/","title":{"rendered":"MAIOR EVO ONE con vetro a tutta altezza"},"content":{"rendered":"\n\n\t<h3>\t\t\n\t\t\t\t\t\t\t \t\t\t\tNOVIT\u00e0\n\t<\/h3>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/LOGO-MAIOR-EVO_glass-one.png\" alt=\"Logo Maior Evo Glass One\" itemprop=\"image\" height=\"187\" width=\"257\" title=\"LOGO-MAIOR-EVO_glass-one\" onerror=\"this.style.display='none'\"  \/>\n\t\t\t<a href=\"https:\/\/faraone.it\/parapetti\/cataloghi\/catalogo-maior-evo---levoluzione-dei-parapetti-in-alluminio-e-vetro-tra-innovazione-e-performance\/\" target=\"_blank\" role=\"button\" rel=\"noopener\">\n\t\t\t\t\t\t\tScarica il catalogo Maior EVO\n\t\t\t\t\t<\/a>\n<h1>\n\t\tIl parapetto con vetro a tutta altezza e passamano a sezione rettangolare\n\t<\/h1>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/CERTIFIED-MAIOR-EVO-bianco.png\" alt=\"Logo Certified Maior Evo - bianco\" itemprop=\"image\" height=\"216\" width=\"216\" title=\"CERTIFIED-MAIOR-EVO-bianco\" onerror=\"this.style.display='none'\"  \/>\n\t\t\t\t<img src=\"https:\/\/faraone.it\/app\/plugins\/bb-plugin\/img\/pixel.png\" alt=\"\" itemprop=\"image\" onerror=\"this.style.display='none'\"  \/>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/sistema-brevettato.png\" alt=\"Sistema brevettato Maior\" itemprop=\"image\" height=\"297\" width=\"231\" title=\"sistema-brevettato\" onerror=\"this.style.display='none'\"  \/>\n\t<p>SISTEMA BREVETTATO<\/p>\n\t<h3>Modelli<\/h3>\n\t<h2>Maior Evo One\u00a0 con fissaggio<\/h2>\n<h2>a pavimento e vetro esterno<\/h2>\n\t<p>Utilizzabile sia per uso esterno che interno.<\/p>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-A.jpg\" alt=\"Installazione parapetto in vetro Maior One - A\" itemprop=\"image\" height=\"1125\" width=\"2071\" title=\"Maior-One-A\" onerror=\"this.style.display='none'\"  \/>\n\t\t\t\t\t\t<h4 tabindex=\"0\">Sezione Maior Evo One &#8211; Modello A<\/h4>\n\t\t\t<div class=\"fl-builder-content fl-builder-content-89866 fl-builder-template fl-builder-row-template fl-builder-global-templates-locked\" data-post-id=\"89866\"><div class=\"fl-row fl-row-fixed-width fl-row-bg-none fl-node-6835ad897118f\" data-node=\"6835ad897118f\">\n\t<div class=\"fl-row-content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"fl-row-content fl-row-fixed-width fl-node-content\">\n\t\t\n<div class=\"fl-col-group fl-node-6835ad8971b5d\" data-node=\"6835ad8971b5d\">\n\t\t\t<div class=\"fl-col fl-node-6835ad8971c6e\" data-node=\"6835ad8971c6e\">\n\t<div class=\"fl-col-content fl-node-content\">\n\t\t\t<div class=\"fl-module fl-module-photo fl-node-6835ad9c578e4\" data-node=\"6835ad9c578e4\">\n\t<div class=\"fl-module-content fl-node-content\">\n\t\t<div class=\"fl-photo fl-photo-align-center\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t<div class=\"fl-photo-content fl-photo-img-jpg\">\n\t\t\t\t<img loading=\"lazy\" class=\"fl-photo-img wp-image-89847 size-full\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-A-2-scaled.jpg\" alt=\"Installazione parapetto in vetro Maior One\" itemprop=\"image\" height=\"2560\" width=\"1552\" title=\"Maior-One-A-2\" srcset=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-A-2-scaled.jpg 1552w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-A-2-728x1200.jpg 728w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-A-2-768x1267.jpg 768w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-A-2-931x1536.jpg 931w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-A-2-1242x2048.jpg 1242w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-A-2-900x1485.jpg 900w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-A-2-1400x2309.jpg 1400w\" sizes=\"(max-width: 1552px) 100vw, 1552px\" \/>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"uabb-js-breakpoint\" style=\"display: none;\"><\/div>\t\t\n\t<h2>Maior Evo One con fissaggio<br \/>\nlaterale e vetro esterno a<br \/>\ntutta altezza<\/h2>\n\t<p>Adatto per uso esterno.<\/p>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-B.jpg\" alt=\"Installazione parapetto in vetro Maior One - B\" itemprop=\"image\" height=\"1125\" width=\"2071\" title=\"Maior-One-B\" onerror=\"this.style.display='none'\"  \/>\n\t\t\t\t\t\t<h4 tabindex=\"0\">Sezione Maior Evo One &#8211; Modello B<\/h4>\n\t\t\t<div class=\"fl-builder-content fl-builder-content-89871 fl-builder-template fl-builder-row-template fl-builder-global-templates-locked\" data-post-id=\"89871\"><div class=\"fl-row fl-row-fixed-width fl-row-bg-none fl-node-6835afad27bde\" data-node=\"6835afad27bde\">\n\t<div class=\"fl-row-content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"fl-row-content fl-row-fixed-width fl-node-content\">\n\t\t\n<div class=\"fl-col-group fl-node-6835afad2807d\" data-node=\"6835afad2807d\">\n\t\t\t<div class=\"fl-col fl-node-6835afad2817e\" data-node=\"6835afad2817e\">\n\t<div class=\"fl-col-content fl-node-content\">\n\t\t\t<div class=\"fl-module fl-module-photo fl-node-6835afe3200a7\" data-node=\"6835afe3200a7\">\n\t<div class=\"fl-module-content fl-node-content\">\n\t\t<div class=\"fl-photo fl-photo-align-center\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t<div class=\"fl-photo-content fl-photo-img-jpg\">\n\t\t\t\t<img loading=\"lazy\" class=\"fl-photo-img wp-image-89849 size-full\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-B-2-scaled.jpg\" alt=\"Installazione parapetto in vetro Maior One\" itemprop=\"image\" height=\"2560\" width=\"1552\" title=\"Maior-One-B-2\" srcset=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-B-2-scaled.jpg 1552w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-B-2-728x1200.jpg 728w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-B-2-768x1267.jpg 768w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-B-2-931x1536.jpg 931w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-B-2-1242x2048.jpg 1242w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-B-2-900x1485.jpg 900w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-B-2-1400x2309.jpg 1400w\" sizes=\"(max-width: 1552px) 100vw, 1552px\" \/>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"uabb-js-breakpoint\" style=\"display: none;\"><\/div>\t\t\n\t<h2>Maior Evo One con fissaggio laterale e vetro interno<\/h2>\n\t<p>Ideale per ballatoio in uso esterno e interno.<\/p>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-C.jpg\" alt=\"Installazione parapetto in vetro Maior One - C\" itemprop=\"image\" height=\"1125\" width=\"2071\" title=\"Maior-One-C\" onerror=\"this.style.display='none'\"  \/>\n\t\t\t\t\t\t<h4 tabindex=\"0\">Sezione Maior Evo One &#8211; Modello C<\/h4>\n\t\t\t<div class=\"fl-builder-content fl-builder-content-89872 fl-builder-template fl-builder-row-template fl-builder-global-templates-locked\" data-post-id=\"89872\"><div class=\"fl-row fl-row-fixed-width fl-row-bg-none fl-node-6835afb7e2486\" data-node=\"6835afb7e2486\">\n\t<div class=\"fl-row-content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"fl-row-content fl-row-fixed-width fl-node-content\">\n\t\t\n<div class=\"fl-col-group fl-node-6835afb7e4078\" data-node=\"6835afb7e4078\">\n\t\t\t<div class=\"fl-col fl-node-6835afb7e4180\" data-node=\"6835afb7e4180\">\n\t<div class=\"fl-col-content fl-node-content\">\n\t\t\t<div class=\"fl-module fl-module-photo fl-node-6835afec120b4\" data-node=\"6835afec120b4\">\n\t<div class=\"fl-module-content fl-node-content\">\n\t\t<div class=\"fl-photo fl-photo-align-center\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t<div class=\"fl-photo-content fl-photo-img-jpg\">\n\t\t\t\t<img loading=\"lazy\" class=\"fl-photo-img wp-image-89851 size-full\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-C-2-scaled.jpg\" alt=\"Installazione parapetto in vetro Maior One\" itemprop=\"image\" height=\"2560\" width=\"1552\" title=\"Maior-One-C-2\" srcset=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-C-2-scaled.jpg 1552w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-C-2-728x1200.jpg 728w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-C-2-768x1267.jpg 768w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-C-2-931x1536.jpg 931w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-C-2-1242x2048.jpg 1242w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-C-2-900x1485.jpg 900w, https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Maior-One-C-2-1400x2309.jpg 1400w\" sizes=\"(max-width: 1552px) 100vw, 1552px\" \/>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"uabb-js-breakpoint\" style=\"display: none;\"><\/div>\t\t\n\t<h3>Dettagli tecnici<\/h3>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/distanza-piantoni.png\" alt=\"distanza tra i piantoni parapetto Maior Evo\" itemprop=\"image\" height=\"500\" width=\"500\" title=\"distanza-piantoni\" onerror=\"this.style.display='none'\"  \/>\n\t<p>Distanza piantoni<\/p>\n\t<p>Passo piantoni 1500 mm per cat. C3<\/p>\n<p>Passo piantoni 2000 mm per cat. C2<\/p>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/altezza-piantoni.png\" alt=\"Altezza vetro parapetto Maior Evo\" itemprop=\"image\" height=\"500\" width=\"500\" title=\"altezza-piantoni\" onerror=\"this.style.display='none'\"  \/>\n\t<p>Altezza piantoni<\/p>\n\t<p>Altezza da terra 1100 mm<\/p>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/corrimano-rettangolare-maior_1.png\" alt=\"Corrimano Rettangolare\" itemprop=\"image\" height=\"500\" width=\"500\" title=\"corrimano-rettangolare-maior_1\" onerror=\"this.style.display='none'\"  \/>\n\t<p>Corrimano rettangolare<\/p>\n\t<p>Con porta vetro integrato<\/p>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Icona_spessore-vetro_66@2000x.png\" alt=\"Spessore vetro parapetto Maior Evo\" itemprop=\"image\" height=\"2520\" width=\"2520\" title=\"Icona_spessore vetro_6+6@2000x\" onerror=\"this.style.display='none'\"  \/>\n\t<p>Spessore vetro<\/p>\n\t<p>Vetro 6+6 Float per cat. C2<\/p>\n<p>Vetro 6+6 Temperato per cat. C3<\/p>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/spinta_maior.png\" alt=\"Resistenza spinta parapetto Maior Evo\" itemprop=\"image\" height=\"500\" width=\"500\" title=\"spinta_maior\" onerror=\"this.style.display='none'\"  \/>\n\t<p>Resistenza alla spinta<\/p>\n\t<p>Testata fino a 450 kg\/m<\/p>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/03\/gamma-colori-maior-evo.jpeg\" alt=\"gamma colori maior evo\" itemprop=\"image\" height=\"375\" width=\"600\" title=\"gamma-colori-maior-evo\" onerror=\"this.style.display='none'\"  \/>\n\t<h2>Personalizza<\/h2>\n<h2>i colori dei profili per un design unico<\/h2>\n\t<ul>\n\t\t<li>\t\t\t\t\n\t\t<h3>Finiture base:<\/h3><p>Bianco RAL 9010 opaco o Silver verniciato.<\/p><\/li><li>\t\t\t\t\n\t\t<h3>Finiture su richiesta:<\/h3><p>possibilit\u00e0 di scegliere tra pi\u00f9 di 2000 colori RAL.<\/p><\/li>\t<\/ul>\n\t\t\t<a href=\"https:\/\/faraone.it\/parapetti\/cataloghi\/catalogo-maior-evo---levoluzione-dei-parapetti-in-alluminio-e-vetro-tra-innovazione-e-performance\/\" target=\"_blank\" role=\"button\" rel=\"noopener\">\n\t\t\t\t\t\t\tScopri di pi\u00f9 nel catalogo Maior Evo\n\t\t\t\t\t<\/a>\n\t<h2>Nuovo design minimale<\/h2>\n<h2>ed elegante<\/h2>\n\t<h4>Design minimale e razionale, per un aspetto contemporaneo che si adatta a qualsiasi ambiente.<\/h4>\n\t\t\t<a href=\"https:\/\/faraone.it\/parapetti\/cataloghi\/catalogo-maior-evo---levoluzione-dei-parapetti-in-alluminio-e-vetro-tra-innovazione-e-performance\/\" target=\"_blank\" role=\"button\" rel=\"noopener\">\n\t\t\t\t\t\t\tScopri di pi\u00f9 nel catalogo Maior Evo\n\t\t\t\t\t<\/a>\n\t<meta itemprop=\"url\" content=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/03\/Presentazione-maior-evo-ok.mp4\" \/><div style=\"width: 640px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-89191-1\" width=\"640\" height=\"360\" poster=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/03\/Maior-evo-sicurezza.jpg\" preload=\"none\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/03\/Presentazione-maior-evo-ok.mp4?_=1\" \/><a href=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/03\/Presentazione-maior-evo-ok.mp4\">https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/03\/Presentazione-maior-evo-ok.mp4<\/a><\/video><\/div>\n\t<h2>Pi\u00f9 trasparenza certificata<\/h2>\n\t<p>L&#8217;interasse dei piantoni e la trasparenza del vetro garantiscono protezione e sicurezza senza compromettere la vista.<\/p>\n<p>&nbsp;<\/p>\n<p>La balaustra ha superato rigorosi test di sicurezza e prestazioni, garantendo affidabilit\u00e0 e durata nel tempo per l&#8217;utilizzo in<\/p>\n\t<h4><strong>categoria C2 e C3<\/strong><\/h4>\n\t<p>secondo la UNI 11678:2017.<\/p>\n\t\t\t<a href=\"https:\/\/faraone.it\/parapetti\/cataloghi\/catalogo-maior-evo---levoluzione-dei-parapetti-in-alluminio-e-vetro-tra-innovazione-e-performance\/\" target=\"_blank\" role=\"button\" rel=\"noopener\">\n\t\t\t\t\t\t\tScopri di pi\u00f9 nel catalogo Maior Evo\n\t\t\t\t\t<\/a>\n\t<h2>Accessori innovativi<\/h2>\n\t<p>Nuovi elementi e dettagli in alluminio che ottimizzano il design, garantendo al contempo una maggiore stabilit\u00e0 e funzionalit\u00e0. Un equilibrio perfetto tra estetica e performance.<\/p>\n\t\t\t<a href=\"https:\/\/faraone.it\/parapetti\/cataloghi\/catalogo-maior-evo---levoluzione-dei-parapetti-in-alluminio-e-vetro-tra-innovazione-e-performance\/\" target=\"_blank\" role=\"button\" rel=\"noopener\">\n\t\t\t\t\t\t\tScopri di pi\u00f9 nel catalogo Maior Evo\n\t\t\t\t\t<\/a>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/accessori-parapetti-maior-evo.jpg\" alt=\"Accessori parapetti in vetro Maior EvO\" itemprop=\"image\" height=\"1067\" width=\"1600\" title=\"accessori-parapetti-maior-evo\" onerror=\"this.style.display='none'\"  \/>\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/montaggio-parapetti-maior-evo.jpg\" alt=\"Montaggio parapetti in vetro Maior EvO\" itemprop=\"image\" height=\"1067\" width=\"1600\" title=\"montaggio-parapetti-maior-evo\" onerror=\"this.style.display='none'\"  \/>\n\t<h2>Posa semplificata<\/h2>\n\t<p>Il sistema di installazione rende la posa rapida e senza complicazioni, risolvendo le criticit\u00e0 comuni alla precedente collezione e assicurando una perfetta aderenza e stabilit\u00e0 fin dal primo montaggio.<\/p>\n\t\t\t<a href=\"https:\/\/faraone.it\/parapetti\/cataloghi\/catalogo-maior-evo---levoluzione-dei-parapetti-in-alluminio-e-vetro-tra-innovazione-e-performance\/\" target=\"_blank\" role=\"button\" rel=\"noopener\">\n\t\t\t\t\t\t\tScopri di pi\u00f9 nel catalogo Maior Evo\n\t\t\t\t\t<\/a>\n<h3>\n\t\tCosa pensa chi ha usato<br \/>le nostre tecnologie?\n\t<\/h3>\n\t\t\t<p>&#8220;Sono stato tra i primi a provare i profili di NINFA la serie 6 di Faraone.<br \/>Come sempre, Faraone ha saputo apportare delle innovazioni a un prodotto gi\u00e0 valido, la serie Ninfa 5, rendendo i modelli della nuova serie 6 migliori sotto molti aspetti e cercando di facilitare il lavoro di progettazione e di installazione di noi artigiani. Primo tra tutti, la possibilit\u00e0 di avere un profilo gi\u00e0 disponibile con le relazioni di calcolo, questo semplifica di molto l&#8217;approccio con i clienti e soprattutto con gli enti pubblici. <br \/>I nuovi accessori che velocizzano di gran lunga la movimentazione e il taglio, permettendo in un secondo tempo di montare il nuovo sistema per fissare il vetro in base allo spessore.<br \/>E infine, un plauso speciale a Faraone, per il profilo che reputo il pi\u00f9 interessante della nuova serie, il profilo che mancava. Il Ninfa 116. Tra le sue caratteristiche pi\u00f9 apprezzate sottolineo il fatto di poter avere il vetro il pi\u00f9 possibile allineato verso l&#8217;esterno, e la praticit\u00e0 del fissaggio per la versione affogata, che rende praticamente impossibile il rischio del passaggio dell&#8217;acqua.&#8221;<\/p>\u00a0<em><strong>\u00a0Michele Malisan<\/strong><\/em><em>Vetreria Artistica Malisan<\/em>\u00a0\t\t\n\t\t\t<p>&#8220;I sistemi NINFA la serie 6 hanno la praticit\u00e0 di poter essere posati molto velocemente e, per la regolazione e il serraggio del vetro, occorre quasi la met\u00e0 del tempo.<br \/>Dal mio punta di vista tecnico li trovo ancora pi\u00f9 solidi rispetto alla precedente serie, inoltre apprezzo la scelta di utilizzare barre M12 perch\u00e9 consente di avere calcoli pi\u00f9 precisi per i carichi puntuali degli ancoraggi.<br \/>La possibilit\u00e0 di avere lo stesso profilo di base con due kit vetro intercambiabili \u00e8 sicuramente pi\u00f9 agevole soprattutto quando il cliente ha fretta di predisporre i profili per completare le successive lavorazioni&#8221;.<\/p>\u00a0<em><strong>Alberto Resmini<\/strong><\/em><em>Vetreria Bergamasca Tecnovetro<\/em>\u00a0\u00a0\u00a0\u00a0\u00a0\t\t\n\t\t\t<p>&#8220;L&#8217;arrivo della serie 6 di Ninfa ha portato un sistema pi\u00f9 performante migliorando il design.<br \/>La fase di montaggio \u00e8 molto semplice e veloce.<br \/>La novit\u00e0 pi\u00f9 eclatante della serie \u00e8 l&#8217;inserimento del nuovo modello Ninfa 116. La sua particolarit\u00e0 \u00e8 il montaggio a filo esterno. Un tipo di fissaggio ancora pi\u00f9 sicuro, non in corrispondenza del vetro e di conseguenza con meno rischi d&#8217;infiltrazioni. In poche parole TOP!&#8221;<\/p>\u00a0<em><strong>Alessandro Rossi<\/strong><\/em><em>Vetreria Aurora<\/em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\t\t\n\t<p>Potrebbe interessarti anche<\/p>\n\t<p>altri modelli di parapetti Faraone<\/p>\n\t\t<h2><a href=\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-plus-con-vetro-distanziato-dal-passamano\/\" target=\"_blank\" rel=\"noopener\">MAIOR EVO <b>GLASS PLUS<\/b><\/a><\/h2>\n\t\t\t\t<a href=\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-plus-con-vetro-distanziato-dal-passamano\/\" target=\"_blank\" rel=\"noopener\" itemprop=\"url\">\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/04\/Parapetti-in-vetro-e-alluminio-maior-evo-23.jpg\" alt=\"parapetti in vetro e alluminio Maior Evo Plus\" itemprop=\"image\" height=\"1067\" width=\"1600\" title=\"Parapetti-in-vetro-e-alluminio-maior-evo-23\" onerror=\"this.style.display='none'\"  \/>\n\t\t\t\t<\/a>\n\t\t\tCon profili reggi-vetro continui<br \/>\n(corrimano in alluminio rettangolare o tondo)\n\t\t\t<a href=\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-plus-con-vetro-distanziato-dal-passamano\/\" target=\"_blank\" role=\"button\" rel=\"noopener\">\n\t\t\t\t\t\t\tScopri di pi\u00f9\n\t\t\t\t\t<\/a>\n\t\t<h2><a href=\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-vision-con-vetro-sorretto-da-manine\/\" target=\"_blank\" rel=\"noopener\">MAIOR EVO <b>GLASS VISION<\/b><\/a><\/h2>\n\t\t\t\t<a href=\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-vision-con-vetro-sorretto-da-manine\/\" target=\"_blank\" rel=\"noopener\" itemprop=\"url\">\n\t\t\t\t<img loading=\"lazy\" src=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/03\/Parapetti-in-vetro-e-alluminio-maior-evo12.jpg\" alt=\"parapetti in vetro e alluminio Maior Evo Vision\" itemprop=\"image\" height=\"1067\" width=\"1600\" title=\"Parapetti-in-vetro-e-alluminio-maior-evo12\" onerror=\"this.style.display='none'\"  \/>\n\t\t\t\t<\/a>\n\t\t\tCon il vetro fissato da accessori agli angoli<br \/>\n(corrimano in alluminio rettangolare o tondo)\n\t\t\t<a href=\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-vision-con-vetro-sorretto-da-manine\/\" target=\"_blank\" role=\"button\" rel=\"noopener\">\n\t\t\t\t\t\t\tScopri di pi\u00f9\n\t\t\t\t\t<\/a>\n\t<p>Vuoi sapere di pi\u00f9<\/p>\n<p>sui parapetti Maior Evo One?<\/p>\n\n","protected":false},"author":26,"template":"","collezione-balaustre":[23],"balustrade-function":[],"balustrade-attachment":[],"balustrade-type":[],"balustrade-finish":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MAIOR EVO ONE con vetro a tutta altezza &gt; Faraone Parapetti<\/title>\n<meta name=\"description\" content=\"MAIOR EVO ONE con vetro a tutta altezza. Il parapetto con massima trasparenza, sicurezza certificata e design minimalista. Ideale per balconi, terrazzi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-one-con-vetro-a-tutta-altezza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MAIOR EVO ONE con vetro a tutta altezza &gt; Faraone Parapetti\" \/>\n<meta property=\"og:description\" content=\"MAIOR EVO ONE con vetro a tutta altezza. Il parapetto con massima trasparenza, sicurezza certificata e design minimalista. Ideale per balconi, terrazzi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-one-con-vetro-a-tutta-altezza\/\" \/>\n<meta property=\"og:site_name\" content=\"Faraone Parapetti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Faraone-Srl\/321807227844860\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T10:20:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/03\/Parapetti-in-vetro-e-alluminio-maior-evo10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Faraonesrl\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\">\n\t<meta name=\"twitter:data1\" content=\"7 minuti\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/faraone.it\/parapetti\/#website\",\"url\":\"https:\/\/faraone.it\/parapetti\/\",\"name\":\"Faraone Parapetti\",\"description\":\"Parapetti, scale, pensiline, facciate continue, divisori, pareti in vetro.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/faraone.it\/parapetti\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-one-con-vetro-a-tutta-altezza\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/03\/Parapetti-in-vetro-e-alluminio-maior-evo10.jpg\",\"contentUrl\":\"https:\/\/faraone-s3.s3.amazonaws.com\/uploads\/sites\/6\/2025\/03\/Parapetti-in-vetro-e-alluminio-maior-evo10.jpg\",\"width\":1600,\"height\":1067,\"caption\":\"parapetti in vetro e alluminio Maior Evo\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-one-con-vetro-a-tutta-altezza\/#webpage\",\"url\":\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-one-con-vetro-a-tutta-altezza\/\",\"name\":\"MAIOR EVO ONE con vetro a tutta altezza &gt; Faraone Parapetti\",\"isPartOf\":{\"@id\":\"https:\/\/faraone.it\/parapetti\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-one-con-vetro-a-tutta-altezza\/#primaryimage\"},\"datePublished\":\"2025-04-04T09:55:59+00:00\",\"dateModified\":\"2026-07-14T10:20:58+00:00\",\"description\":\"MAIOR EVO ONE con vetro a tutta altezza. Il parapetto con massima trasparenza, sicurezza certificata e design minimalista. Ideale per balconi, terrazzi.\",\"breadcrumb\":{\"@id\":\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-one-con-vetro-a-tutta-altezza\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-one-con-vetro-a-tutta-altezza\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-one-con-vetro-a-tutta-altezza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/faraone.it\/parapetti\/\",\"url\":\"https:\/\/faraone.it\/parapetti\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/faraone.it\/parapetti\/prodotto-parapetti\/maior-evo-one-con-vetro-a-tutta-altezza\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/faraone.it\/parapetti\/wp-json\/wp\/v2\/balaustre\/89191"}],"collection":[{"href":"https:\/\/faraone.it\/parapetti\/wp-json\/wp\/v2\/balaustre"}],"about":[{"href":"https:\/\/faraone.it\/parapetti\/wp-json\/wp\/v2\/types\/balaustre"}],"author":[{"embeddable":true,"href":"https:\/\/faraone.it\/parapetti\/wp-json\/wp\/v2\/users\/26"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/faraone.it\/parapetti\/wp-json\/wp\/v2\/media\/88965"}],"wp:attachment":[{"href":"https:\/\/faraone.it\/parapetti\/wp-json\/wp\/v2\/media?parent=89191"}],"wp:term":[{"taxonomy":"collezione-balaustre","embeddable":true,"href":"https:\/\/faraone.it\/parapetti\/wp-json\/wp\/v2\/collezione-balaustre?post=89191"},{"taxonomy":"balustrade-function","embeddable":true,"href":"https:\/\/faraone.it\/parapetti\/wp-json\/wp\/v2\/balustrade-function?post=89191"},{"taxonomy":"balustrade-attachment","embeddable":true,"href":"https:\/\/faraone.it\/parapetti\/wp-json\/wp\/v2\/balustrade-attachment?post=89191"},{"taxonomy":"balustrade-type","embeddable":true,"href":"https:\/\/faraone.it\/parapetti\/wp-json\/wp\/v2\/balustrade-type?post=89191"},{"taxonomy":"balustrade-finish","embeddable":true,"href":"https:\/\/faraone.it\/parapetti\/wp-json\/wp\/v2\/balustrade-finish?post=89191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}